{"id":18992,"count":1,"description":"","link":"https:\/\/www.yvesbeck.wine\/fr\/tag\/tour-puyblanquet-2\/","name":"Tour Puyblanquet","slug":"tour-puyblanquet-2","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Tour Puyblanquet Archive - yvesbeck.wine<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.yvesbeck.wine\/fr\/tag\/tour-puyblanquet-2\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tour Puyblanquet Archive - yvesbeck.wine\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.yvesbeck.wine\/fr\/tag\/tour-puyblanquet-2\/\" \/>\n<meta property=\"og:site_name\" content=\"yvesbeck.wine\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.yvesbeck.wine\/wp-content\/uploads\/2019\/05\/Primeurs-2018-logo-yvesbeck.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1158\" \/>\n\t<meta property=\"og:image:height\" content=\"384\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@beckustator\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.yvesbeck.wine\\\/fr\\\/tag\\\/tour-puyblanquet-2\\\/\",\"url\":\"https:\\\/\\\/www.yvesbeck.wine\\\/fr\\\/tag\\\/tour-puyblanquet-2\\\/\",\"name\":\"Tour Puyblanquet Archive - yvesbeck.wine\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.yvesbeck.wine\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.yvesbeck.wine\\\/fr\\\/tag\\\/tour-puyblanquet-2\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.yvesbeck.wine\\\/fr\\\/tag\\\/tour-puyblanquet-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.yvesbeck.wine\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tour Puyblanquet\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.yvesbeck.wine\\\/#website\",\"url\":\"https:\\\/\\\/www.yvesbeck.wine\\\/\",\"name\":\"yvesbeck.wine\",\"description\":\"Beckustator\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.yvesbeck.wine\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.yvesbeck.wine\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.yvesbeck.wine\\\/#organization\",\"name\":\"yvesbeck.wine\",\"url\":\"https:\\\/\\\/www.yvesbeck.wine\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.yvesbeck.wine\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.yvesbeck.wine\\\/wp-content\\\/uploads\\\/frontend\\\/2016\\\/07\\\/20160722-Logo-Sidebar.png\",\"contentUrl\":\"https:\\\/\\\/www.yvesbeck.wine\\\/wp-content\\\/uploads\\\/frontend\\\/2016\\\/07\\\/20160722-Logo-Sidebar.png\",\"width\":376,\"height\":200,\"caption\":\"yvesbeck.wine\"},\"image\":{\"@id\":\"https:\\\/\\\/www.yvesbeck.wine\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/beckustator\",\"https:\\\/\\\/x.com\\\/beckustator\",\"https:\\\/\\\/www.instagram.com\\\/beckustator\",\"https:\\\/\\\/www.linkedin.com\\\/in\\\/yvesbeck\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Tour Puyblanquet Archive - yvesbeck.wine","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.yvesbeck.wine\/fr\/tag\/tour-puyblanquet-2\/","og_locale":"fr_FR","og_type":"article","og_title":"Tour Puyblanquet Archive - yvesbeck.wine","og_url":"https:\/\/www.yvesbeck.wine\/fr\/tag\/tour-puyblanquet-2\/","og_site_name":"yvesbeck.wine","og_image":[{"width":1158,"height":384,"url":"https:\/\/www.yvesbeck.wine\/wp-content\/uploads\/2019\/05\/Primeurs-2018-logo-yvesbeck.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@beckustator","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.yvesbeck.wine\/fr\/tag\/tour-puyblanquet-2\/","url":"https:\/\/www.yvesbeck.wine\/fr\/tag\/tour-puyblanquet-2\/","name":"Tour Puyblanquet Archive - yvesbeck.wine","isPartOf":{"@id":"https:\/\/www.yvesbeck.wine\/#website"},"breadcrumb":{"@id":"https:\/\/www.yvesbeck.wine\/fr\/tag\/tour-puyblanquet-2\/#breadcrumb"},"inLanguage":"fr-FR"},{"@type":"BreadcrumbList","@id":"https:\/\/www.yvesbeck.wine\/fr\/tag\/tour-puyblanquet-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.yvesbeck.wine\/fr\/"},{"@type":"ListItem","position":2,"name":"Tour Puyblanquet"}]},{"@type":"WebSite","@id":"https:\/\/www.yvesbeck.wine\/#website","url":"https:\/\/www.yvesbeck.wine\/","name":"yvesbeck.wine","description":"Beckustator","publisher":{"@id":"https:\/\/www.yvesbeck.wine\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.yvesbeck.wine\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.yvesbeck.wine\/#organization","name":"yvesbeck.wine","url":"https:\/\/www.yvesbeck.wine\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.yvesbeck.wine\/#\/schema\/logo\/image\/","url":"https:\/\/www.yvesbeck.wine\/wp-content\/uploads\/frontend\/2016\/07\/20160722-Logo-Sidebar.png","contentUrl":"https:\/\/www.yvesbeck.wine\/wp-content\/uploads\/frontend\/2016\/07\/20160722-Logo-Sidebar.png","width":376,"height":200,"caption":"yvesbeck.wine"},"image":{"@id":"https:\/\/www.yvesbeck.wine\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/beckustator","https:\/\/x.com\/beckustator","https:\/\/www.instagram.com\/beckustator","https:\/\/www.linkedin.com\/in\/yvesbeck\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.yvesbeck.wine\/fr\/wp-json\/wp\/v2\/tags\/18992","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.yvesbeck.wine\/fr\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.yvesbeck.wine\/fr\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.yvesbeck.wine\/fr\/wp-json\/wp\/v2\/posts?tags=18992"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}