{"id":148806,"date":"2026-02-28T16:00:37","date_gmt":"2026-02-28T15:00:37","guid":{"rendered":"https:\/\/www.yvesbeck.wine\/?p=148806"},"modified":"2026-03-02T10:20:26","modified_gmt":"2026-03-02T09:20:26","slug":"mas-des-quernes","status":"publish","type":"post","link":"https:\/\/www.yvesbeck.wine\/fr\/mas-des-quernes\/","title":{"rendered":"Mas des Quernes : 6 terroirs et 14 cuv\u00e9es"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong>Le Mas des Quernes est situ\u00e9 dans une magnifique r\u00e9gion, \u00e0 Montpeyroux. Un site \u00e0 d\u00e9couvrir pour fl\u00e2ner, d\u00e9guster, passer des vacances et sourire \u00e0 longueur de journ\u00e9e !<\/strong><\/p>\n<h4 style=\"text-align: justify;\"><strong>Un peu d&rsquo;histoire<\/strong><\/h4>\n<p style=\"text-align: justify;\">En 2009 Peter Riegel et Jean Natoli ont un coup de foudre pour 11ha de vignes d&rsquo;un seul tenant \u00e0 Montpeyroux. C&rsquo;est le d\u00e9but du Mas des Quernes et la premi\u00e8re r\u00e9colte a lieu en 2010. Apr\u00e8s trois ans de certification, le label BIO est obtenu en 2012. C&rsquo;est \u00e9galement cette ann\u00e9e-l\u00e0 que l&rsquo;on vinifie pour la premi\u00e8re fois dans les nouvelles caves de Montpeyroux.<\/p>\n<h4 style=\"text-align: justify;\"><strong>Six terroirs diff\u00e9renci\u00e9s<\/strong><\/h4>\n<p style=\"text-align: justify;\">On compte six terroirs diff\u00e9renci\u00e9s au <a href=\"https:\/\/mas-des-quernes.com\/\" target=\"_blank\" rel=\"noopener\">Mas des Quernes<\/a> :<\/p>\n<ul style=\"text-align: justify;\">\n<li>Le Puych de Cambyse (Galets)<\/li>\n<li>Les Marnes Calcaires<\/li>\n<li>Le Plateau de Colluvions &#8211; argilo-calcaire et coteau d&rsquo;\u00e9pandage en cailloutis<\/li>\n<li>Les Petits Travers &#8211; Succession de petites parcelles en coteau et en terrasses<\/li>\n<li>Mas Cascal (au pied du Mont Ventoux, \u00e0 135km du domaine)<\/li>\n<li>Le Barry Montpeyroux (Marnes bleues)<\/li>\n<\/ul>\n<h4 style=\"text-align: justify;\"><strong>14 cuv\u00e9es <\/strong><\/h4>\n<p style=\"text-align: justify;\">Ce ne sont pas moins de 14 cuv\u00e9es diff\u00e9rentes que compte le Mas des Quernes.<\/p>\n<p>En Suisse le vin est disponible chez <a href=\"https:\/\/www.daniel-vins.ch\/fr\/\" target=\"_blank\" rel=\"noopener\">daniel-vins.ch<\/a><\/p>\n<hr \/>\n<h4><\/h4>\n<h4 style=\"text-align: center;\"><strong>Les vins d\u00e9gust\u00e9s par <a href=\"https:\/\/www.yvesbeck.wine\/fr\/yves-beck\/\" target=\"_blank\" rel=\"noopener\">Yves Beck<\/a> en 2025<\/strong><\/h4>\n<h5 style=\"text-align: justify;\"><strong>Le Querne 2020<\/strong><\/h5>\n<p style=\"text-align: justify;\">Le Querne 2020 se caract\u00e9rise par la profondeur qu&rsquo;il affiche d&#8217;embl\u00e9e, d\u00e8s les premiers effluves. Les notes de f\u00e8ves de cacao coupl\u00e9es \u00e0 des parfums de griottes, de cassis et de poivre ne font que souligner la complexit\u00e9 pr\u00e9sente. Invitant d\u00e8s les premi\u00e8res gorg\u00e9es, le vin peut compter sur l&rsquo;appui de tannins suaves qui offrent de la largeur. Ils sont second\u00e9s par la structure qui assure une fra\u00eecheur bienvenue en fin de bouche. Un vin gourmand, frais et persistant. Belle r\u00e9ussite. Maintenant &#8211; 2033 <strong>93\/100<\/strong><\/p>\n<h5 style=\"text-align: justify;\"><strong>La Villa Romaine 2020<\/strong><\/h5>\n<p style=\"text-align: justify;\">Carignan, Mourv\u00e8dre, Grenache<br \/>\nLe bouquet de la Villa Romaine 2020 indique que e cru est \u00e9panoui, mais pas fatigu\u00e9 ! Bien au contraire, ses notes de tapenade, de cassis et de cacao annoncent un vin invitant, tandis que le palais pr\u00e9sente des tannins en pleine forme. De pair avec une acidit\u00e9 structurante, assurant la fra\u00eecheur de la finale, ils offrent une assise fiable. Un vin invitant et pr\u00eat \u00e0 \u00eatre savour\u00e9. Maintenant &#8211; 2029 <strong>92\/100<\/strong><\/p>\n<h5 style=\"text-align: justify;\"><strong>La Villa Romaine 2021<\/strong><\/h5>\n<p style=\"text-align: justify;\">Carignan, Mourv\u00e8dre, Grenache, Syrah<br \/>\nPr\u00e9cis et d\u00e9fini, le bouquet de La Villa Romaine 2021 affiche de subtiles nuances d&rsquo;herbes aromatiques, de baies noires, de v\u00e9tiver et de poivre. D\u00e8s l&rsquo;attaque, le vin a un \u00e9vident focus d\u00e9di\u00e9 \u00e0 l&rsquo;\u00e9quilibre. La symbiose entre les c\u00f4t\u00e9s suave, vif, juteux et vigoureux est parfaite ! Un vin salivant, sapide et pr\u00eat \u00e0 \u00eatre savour\u00e9, tout en disposant d&rsquo;un potentiel de garde respectable (m\u00eame s&rsquo;il sera bu avant\u2026 ce qui est de bon augure \u00e9galement !) Maintenant &#8211; 2031 <strong>92\/100<\/strong><\/p>\n<h5 style=\"text-align: justify;\"><strong>Les Cros 2021<\/strong><\/h5>\n<p style=\"text-align: justify;\">Syrah, Grenache, Carignan, Mourv\u00e8dre<br \/>\nBeaucoup de subtilit\u00e9 dans ce bouquet qui r\u00e9v\u00e8le diff\u00e9rentes facettes. Ainsi, il affiche des nuances \u00e9pic\u00e9es, respectivement du poivre noir, du cassis, un peu de caf\u00e9 et des notes de geni\u00e8vre. Le vin se distingue par sa fra\u00eecheur et ses tannins suaves. Ces derniers, parfaitement int\u00e9gr\u00e9s, vont de pair avec une acidit\u00e9 rafra\u00eechissante conciliant densit\u00e9 et temp\u00e9rament. Un vin sapide et pr\u00eat \u00e0 \u00eatre savour\u00e9. Maintenant &#8211; 2031 <strong>92\/100<\/strong><\/p>\n<h5 style=\"text-align: justify;\"><strong>Le Cascal pour Esm\u00e9e 2024<\/strong><\/h5>\n<p style=\"text-align: justify;\">Roussanne, Viognier, Grenache Blanc, Rolle, Muscat \u00e0 Petit Grains<br \/>\nSuperbe bouquet, tant par son intensit\u00e9 que sa pluralit\u00e9. Ainsi, il r\u00e9v\u00e8le moult nuances au travers de tabac blond, de p\u00eaches, de fenouil et de fleurs blanches. Dense et friand en attaque, le vin est cr\u00e9meux et port\u00e9 par de fins amers qui assurent non seulement son expression gustative, mais \u00e9galement sa longueur. Un vin savoureux, structur\u00e9 et persistant. Maintenant &#8211; 2034 <strong>93\/100<\/strong><\/p>\n<p>&nbsp;<\/p>\n<hr \/>\n<p style=\"text-align: center;\"><a href=\"https:\/\/www.yvesbeck.wine\/fr\/categorie-produit\/subscriptions-fr\/\"><span style=\"color: #800000;\"><strong>Abonnez-vous \u00e0 yvesbeck.wine pour seulement CHF. 98.00 par an<br \/>\net acc\u00e9dez \u00e0 39128 notes de d\u00e9gustation<\/strong><\/span><\/a><\/p>\n<hr \/>\n<h4><\/h4>\n<h4><strong>Archives<\/strong><\/h4>\n<h4><strong>La Villa Romaine 2020<\/strong><\/h4>\n<p>Cette cuv\u00e9e est issue des meilleures parcelles du domaine, au pied du causse du Larzac, avec une moyenne d&rsquo;\u00e2ge de vignes de 45 ans sur sol calcaire. L&rsquo;\u00e9levage de 12 mois s&rsquo;est d\u00e9roul\u00e9 dans des barriques de 225 litres (8% neuves), par c\u00e9page et par parcelle. L&rsquo;assemblage (45% Carignan, 30% Mourv\u00e8dre, 25% Grenache) se fait ensuite en cuve o\u00f9 le vin repose 6 mois avant la mise en bouteille.<\/p>\n<p>Ce 2020 regorge de fra\u00eecheur avec des notes de garrigues et de camphre compl\u00e9t\u00e9es par des parfums de fruits noirs et de tabac. Juteux et suave en attaque, le vin confirme la fra\u00eecheur annonc\u00e9e par le bouquet. Son c\u00f4t\u00e9 gourmand et la rondeur de ses tannins invitent \u00e0 le savourer. Un Terrasses de Larzac s\u00e9duisant et convaincant ! Maintenant &#8211; 2030 <strong>92\/100<\/strong><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le Mas des Quernes est situ\u00e9 dans une magnifique r\u00e9gion, \u00e0 Montpeyroux. Un site \u00e0 d\u00e9couvrir pour fl\u00e2ner, d\u00e9guster, passer des vacances et sourire \u00e0 longueur de journ\u00e9e ! Un peu d&rsquo;histoire En 2009 Peter Riegel et Jean Natoli ont un coup de foudre pour 11ha de vignes d&rsquo;un seul tenant \u00e0 Montpeyroux. C&rsquo;est le [&hellip;]<\/p>\n","protected":false},"author":14,"featured_media":163279,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[149],"tags":[9710,13797],"class_list":["post-148806","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-france","tag-languedoc","tag-mas-des-quernes-fr"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Mas des Quernes : 6 terroirs et 14 cuv\u00e9es - Yves Beck<\/title>\n<meta name=\"description\" content=\"A Montpeyroux, AOC Terrasses du Larzac, Mas des Quernes produit des vins bio construits sur la finesse et l&#039;\u00e9quilibre. yvesbeck.wine a go\u00fbt\u00e9\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.yvesbeck.wine\/fr\/mas-des-quernes\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mas des Quernes : 6 terroirs et 14 cuv\u00e9es - Yves Beck\" \/>\n<meta property=\"og:description\" content=\"A Montpeyroux, AOC Terrasses du Larzac, Mas des Quernes produit des vins bio construits sur la finesse et l&#039;\u00e9quilibre. yvesbeck.wine a go\u00fbt\u00e9\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.yvesbeck.wine\/fr\/mas-des-quernes\/\" \/>\n<meta property=\"og:site_name\" content=\"Yves Beck\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/beckustator\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/beckustator\" \/>\n<meta property=\"article:published_time\" content=\"2026-02-28T15:00:37+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-02T09:20:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.yvesbeck.wine\/wp-content\/uploads\/2024\/01\/mas-des-quernes-vignes.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"512\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Yves Beck\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@beckustator\" \/>\n<meta name=\"twitter:site\" content=\"@beckustator\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Yves Beck\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.yvesbeck.wine\/fr\/mas-des-quernes\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.yvesbeck.wine\/fr\/mas-des-quernes\/\"},\"author\":{\"name\":\"Yves Beck\",\"@id\":\"https:\/\/www.yvesbeck.wine\/#\/schema\/person\/33cc92b5916fa8e634fe59f0121a0cad\"},\"headline\":\"Mas des Quernes : 6 terroirs et 14 cuv\u00e9es\",\"datePublished\":\"2026-02-28T15:00:37+00:00\",\"dateModified\":\"2026-03-02T09:20:26+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.yvesbeck.wine\/fr\/mas-des-quernes\/\"},\"wordCount\":802,\"publisher\":{\"@id\":\"https:\/\/www.yvesbeck.wine\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.yvesbeck.wine\/fr\/mas-des-quernes\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.yvesbeck.wine\/wp-content\/uploads\/2024\/01\/mas-des-quernes-vignes.png\",\"keywords\":[\"Languedoc\",\"Mas des Quernes\"],\"articleSection\":[\"France\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.yvesbeck.wine\/fr\/mas-des-quernes\/\",\"url\":\"https:\/\/www.yvesbeck.wine\/fr\/mas-des-quernes\/\",\"name\":\"Mas des Quernes : 6 terroirs et 14 cuv\u00e9es - Yves Beck\",\"isPartOf\":{\"@id\":\"https:\/\/www.yvesbeck.wine\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.yvesbeck.wine\/fr\/mas-des-quernes\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.yvesbeck.wine\/fr\/mas-des-quernes\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.yvesbeck.wine\/wp-content\/uploads\/2024\/01\/mas-des-quernes-vignes.png\",\"datePublished\":\"2026-02-28T15:00:37+00:00\",\"dateModified\":\"2026-03-02T09:20:26+00:00\",\"description\":\"A Montpeyroux, AOC Terrasses du Larzac, Mas des Quernes produit des vins bio construits sur la finesse et l'\u00e9quilibre. yvesbeck.wine a go\u00fbt\u00e9\",\"breadcrumb\":{\"@id\":\"https:\/\/www.yvesbeck.wine\/fr\/mas-des-quernes\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.yvesbeck.wine\/fr\/mas-des-quernes\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.yvesbeck.wine\/fr\/mas-des-quernes\/#primaryimage\",\"url\":\"https:\/\/www.yvesbeck.wine\/wp-content\/uploads\/2024\/01\/mas-des-quernes-vignes.png\",\"contentUrl\":\"https:\/\/www.yvesbeck.wine\/wp-content\/uploads\/2024\/01\/mas-des-quernes-vignes.png\",\"width\":800,\"height\":512,\"caption\":\"Mas des Quernes - Montpeyroux\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.yvesbeck.wine\/fr\/mas-des-quernes\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\/\/www.yvesbeck.wine\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mas des Quernes : 6 terroirs et 14 cuv\u00e9es\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.yvesbeck.wine\/#website\",\"url\":\"https:\/\/www.yvesbeck.wine\/\",\"name\":\"Yves Beck\",\"description\":\"Beckustator\",\"publisher\":{\"@id\":\"https:\/\/www.yvesbeck.wine\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.yvesbeck.wine\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.yvesbeck.wine\/#organization\",\"name\":\"yvesbeck.wine\",\"url\":\"https:\/\/www.yvesbeck.wine\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.yvesbeck.wine\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.yvesbeck.wine\/wp-content\/uploads\/frontend\/2016\/07\/20160722-Logo-Sidebar.png\",\"contentUrl\":\"https:\/\/www.yvesbeck.wine\/wp-content\/uploads\/frontend\/2016\/07\/20160722-Logo-Sidebar.png\",\"width\":376,\"height\":200,\"caption\":\"yvesbeck.wine\"},\"image\":{\"@id\":\"https:\/\/www.yvesbeck.wine\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/beckustator\",\"https:\/\/x.com\/beckustator\",\"https:\/\/www.instagram.com\/beckustator\",\"https:\/\/www.linkedin.com\/in\/yvesbeck\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.yvesbeck.wine\/#\/schema\/person\/33cc92b5916fa8e634fe59f0121a0cad\",\"name\":\"Yves Beck\",\"sameAs\":[\"https:\/\/www.yvesbeck.wine\",\"https:\/\/www.facebook.com\/beckustator\",\"https:\/\/www.instagram.com\/beckustator\",\"https:\/\/www.linkedin\/in\/yvesbeck\"],\"url\":\"https:\/\/www.yvesbeck.wine\/fr\/author\/ddb68\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mas des Quernes : 6 terroirs et 14 cuv\u00e9es - Yves Beck","description":"A Montpeyroux, AOC Terrasses du Larzac, Mas des Quernes produit des vins bio construits sur la finesse et l'\u00e9quilibre. yvesbeck.wine a go\u00fbt\u00e9","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.yvesbeck.wine\/fr\/mas-des-quernes\/","og_locale":"fr_FR","og_type":"article","og_title":"Mas des Quernes : 6 terroirs et 14 cuv\u00e9es - Yves Beck","og_description":"A Montpeyroux, AOC Terrasses du Larzac, Mas des Quernes produit des vins bio construits sur la finesse et l'\u00e9quilibre. yvesbeck.wine a go\u00fbt\u00e9","og_url":"https:\/\/www.yvesbeck.wine\/fr\/mas-des-quernes\/","og_site_name":"Yves Beck","article_publisher":"https:\/\/www.facebook.com\/beckustator","article_author":"https:\/\/www.facebook.com\/beckustator","article_published_time":"2026-02-28T15:00:37+00:00","article_modified_time":"2026-03-02T09:20:26+00:00","og_image":[{"width":800,"height":512,"url":"https:\/\/www.yvesbeck.wine\/wp-content\/uploads\/2024\/01\/mas-des-quernes-vignes.png","type":"image\/png"}],"author":"Yves Beck","twitter_card":"summary_large_image","twitter_creator":"@beckustator","twitter_site":"@beckustator","twitter_misc":{"\u00c9crit par":"Yves Beck","Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.yvesbeck.wine\/fr\/mas-des-quernes\/#article","isPartOf":{"@id":"https:\/\/www.yvesbeck.wine\/fr\/mas-des-quernes\/"},"author":{"name":"Yves Beck","@id":"https:\/\/www.yvesbeck.wine\/#\/schema\/person\/33cc92b5916fa8e634fe59f0121a0cad"},"headline":"Mas des Quernes : 6 terroirs et 14 cuv\u00e9es","datePublished":"2026-02-28T15:00:37+00:00","dateModified":"2026-03-02T09:20:26+00:00","mainEntityOfPage":{"@id":"https:\/\/www.yvesbeck.wine\/fr\/mas-des-quernes\/"},"wordCount":802,"publisher":{"@id":"https:\/\/www.yvesbeck.wine\/#organization"},"image":{"@id":"https:\/\/www.yvesbeck.wine\/fr\/mas-des-quernes\/#primaryimage"},"thumbnailUrl":"https:\/\/www.yvesbeck.wine\/wp-content\/uploads\/2024\/01\/mas-des-quernes-vignes.png","keywords":["Languedoc","Mas des Quernes"],"articleSection":["France"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.yvesbeck.wine\/fr\/mas-des-quernes\/","url":"https:\/\/www.yvesbeck.wine\/fr\/mas-des-quernes\/","name":"Mas des Quernes : 6 terroirs et 14 cuv\u00e9es - Yves Beck","isPartOf":{"@id":"https:\/\/www.yvesbeck.wine\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.yvesbeck.wine\/fr\/mas-des-quernes\/#primaryimage"},"image":{"@id":"https:\/\/www.yvesbeck.wine\/fr\/mas-des-quernes\/#primaryimage"},"thumbnailUrl":"https:\/\/www.yvesbeck.wine\/wp-content\/uploads\/2024\/01\/mas-des-quernes-vignes.png","datePublished":"2026-02-28T15:00:37+00:00","dateModified":"2026-03-02T09:20:26+00:00","description":"A Montpeyroux, AOC Terrasses du Larzac, Mas des Quernes produit des vins bio construits sur la finesse et l'\u00e9quilibre. yvesbeck.wine a go\u00fbt\u00e9","breadcrumb":{"@id":"https:\/\/www.yvesbeck.wine\/fr\/mas-des-quernes\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.yvesbeck.wine\/fr\/mas-des-quernes\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.yvesbeck.wine\/fr\/mas-des-quernes\/#primaryimage","url":"https:\/\/www.yvesbeck.wine\/wp-content\/uploads\/2024\/01\/mas-des-quernes-vignes.png","contentUrl":"https:\/\/www.yvesbeck.wine\/wp-content\/uploads\/2024\/01\/mas-des-quernes-vignes.png","width":800,"height":512,"caption":"Mas des Quernes - Montpeyroux"},{"@type":"BreadcrumbList","@id":"https:\/\/www.yvesbeck.wine\/fr\/mas-des-quernes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.yvesbeck.wine\/fr\/"},{"@type":"ListItem","position":2,"name":"Mas des Quernes : 6 terroirs et 14 cuv\u00e9es"}]},{"@type":"WebSite","@id":"https:\/\/www.yvesbeck.wine\/#website","url":"https:\/\/www.yvesbeck.wine\/","name":"Yves Beck","description":"Beckustator","publisher":{"@id":"https:\/\/www.yvesbeck.wine\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.yvesbeck.wine\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.yvesbeck.wine\/#organization","name":"yvesbeck.wine","url":"https:\/\/www.yvesbeck.wine\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.yvesbeck.wine\/#\/schema\/logo\/image\/","url":"https:\/\/www.yvesbeck.wine\/wp-content\/uploads\/frontend\/2016\/07\/20160722-Logo-Sidebar.png","contentUrl":"https:\/\/www.yvesbeck.wine\/wp-content\/uploads\/frontend\/2016\/07\/20160722-Logo-Sidebar.png","width":376,"height":200,"caption":"yvesbeck.wine"},"image":{"@id":"https:\/\/www.yvesbeck.wine\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/beckustator","https:\/\/x.com\/beckustator","https:\/\/www.instagram.com\/beckustator","https:\/\/www.linkedin.com\/in\/yvesbeck\/"]},{"@type":"Person","@id":"https:\/\/www.yvesbeck.wine\/#\/schema\/person\/33cc92b5916fa8e634fe59f0121a0cad","name":"Yves Beck","sameAs":["https:\/\/www.yvesbeck.wine","https:\/\/www.facebook.com\/beckustator","https:\/\/www.instagram.com\/beckustator","https:\/\/www.linkedin\/in\/yvesbeck"],"url":"https:\/\/www.yvesbeck.wine\/fr\/author\/ddb68\/"}]}},"_links":{"self":[{"href":"https:\/\/www.yvesbeck.wine\/fr\/wp-json\/wp\/v2\/posts\/148806","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.yvesbeck.wine\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.yvesbeck.wine\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.yvesbeck.wine\/fr\/wp-json\/wp\/v2\/users\/14"}],"replies":[{"embeddable":true,"href":"https:\/\/www.yvesbeck.wine\/fr\/wp-json\/wp\/v2\/comments?post=148806"}],"version-history":[{"count":7,"href":"https:\/\/www.yvesbeck.wine\/fr\/wp-json\/wp\/v2\/posts\/148806\/revisions"}],"predecessor-version":[{"id":379247,"href":"https:\/\/www.yvesbeck.wine\/fr\/wp-json\/wp\/v2\/posts\/148806\/revisions\/379247"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.yvesbeck.wine\/fr\/wp-json\/wp\/v2\/media\/163279"}],"wp:attachment":[{"href":"https:\/\/www.yvesbeck.wine\/fr\/wp-json\/wp\/v2\/media?parent=148806"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.yvesbeck.wine\/fr\/wp-json\/wp\/v2\/categories?post=148806"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.yvesbeck.wine\/fr\/wp-json\/wp\/v2\/tags?post=148806"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}